{"id":1358,"date":"2024-03-08T16:18:16","date_gmt":"2024-03-08T16:18:16","guid":{"rendered":"https:\/\/oportunidadesdigitales.online\/redress\/?post_type=product&#038;p=1358"},"modified":"2025-01-17T15:00:25","modified_gmt":"2025-01-17T21:00:25","slug":"rosa-clara","status":"publish","type":"product","link":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/","title":{"rendered":"Rosa Clar\u00e1"},"content":{"rendered":"<p>Vestido de Novia marca Rosa Clara, Talla MX 10 con un solo uso. Se le hicieron ajustes al largo y en tirantes. Es un vestido muy sencillo, el detalle de la parte de arriba es hermoso. Muy c\u00f3modo. Se mand\u00f3 a tintorer\u00eda inmediatamente despu\u00e9s de su uso, se entrega en la misma caja de la tintorer\u00eda donde se ha conservado.<\/p>\n<p>Descuento: 60%<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talla: 10\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Desc: 60%<\/p>\n","protected":false},"featured_media":3076,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[135,29,165,30,117],"product_tag":[118,105,119,45,91,43,106],"class_list":{"0":"post-1358","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-135","7":"product_cat-general","8":"product_cat-mas-de-60-off","9":"product_cat-vestidos-novia","10":"product_cat-rosa-clara","11":"product_tag-preloved-wedding-dresses","12":"product_tag-preowned-dresses","13":"product_tag-rosa-clara","14":"product_tag-vestido-barato","15":"product_tag-vestido-de-novias-segunda-mano","16":"product_tag-vestido-segunda-mano","17":"product_tag-vestidos-preloved","19":"first","20":"instock","21":"sale","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rosa Clar\u00e1 - Re Dress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosa Clar\u00e1 - Re Dress\" \/>\n<meta property=\"og:description\" content=\"Talla: 10\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Desc: 60%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/\" \/>\n<meta property=\"og:site_name\" content=\"Re Dress\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T21:00:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/04\/13.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/\",\"url\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/\",\"name\":\"Rosa Clar\u00e1 - Re Dress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/13.webp\",\"datePublished\":\"2024-03-08T16:18:16+00:00\",\"dateModified\":\"2025-01-17T21:00:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/13.webp\",\"contentUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/13.webp\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/rosa-clara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/redressmx.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rosa Clar\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#website\",\"url\":\"https:\\\/\\\/redressmx.com\\\/\",\"name\":\"Re Dress\",\"description\":\"Somos el marketplace de vestidos pre-loved m\u00e1s exclusivo de M\u00e9xico.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redressmx.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#organization\",\"name\":\"Re Dress\",\"url\":\"https:\\\/\\\/redressmx.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Grupo-144-2.png\",\"contentUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Grupo-144-2.png\",\"width\":345,\"height\":58,\"caption\":\"Re Dress\"},\"image\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosa Clar\u00e1 - Re Dress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/","og_locale":"es_MX","og_type":"article","og_title":"Rosa Clar\u00e1 - Re Dress","og_description":"Talla: 10\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Desc: 60%","og_url":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/","og_site_name":"Re Dress","article_modified_time":"2025-01-17T21:00:25+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/04\/13.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/","url":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/","name":"Rosa Clar\u00e1 - Re Dress","isPartOf":{"@id":"https:\/\/redressmx.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/#primaryimage"},"image":{"@id":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/#primaryimage"},"thumbnailUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/04\/13.webp","datePublished":"2024-03-08T16:18:16+00:00","dateModified":"2025-01-17T21:00:25+00:00","breadcrumb":{"@id":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/#primaryimage","url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/04\/13.webp","contentUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/04\/13.webp","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/redressmx.com\/index.php\/product\/rosa-clara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/redressmx.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/redressmx.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Rosa Clar\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/redressmx.com\/#website","url":"https:\/\/redressmx.com\/","name":"Re Dress","description":"Somos el marketplace de vestidos pre-loved m\u00e1s exclusivo de M\u00e9xico.","publisher":{"@id":"https:\/\/redressmx.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redressmx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redressmx.com\/#organization","name":"Re Dress","url":"https:\/\/redressmx.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redressmx.com\/#\/schema\/logo\/image\/","url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/02\/Grupo-144-2.png","contentUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/02\/Grupo-144-2.png","width":345,"height":58,"caption":"Re Dress"},"image":{"@id":"https:\/\/redressmx.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=1358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/media\/3076"}],"wp:attachment":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=1358"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1358"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}