{"id":7023,"date":"2024-11-27T12:19:20","date_gmt":"2024-11-27T18:19:20","guid":{"rendered":"https:\/\/redressmx.com\/?post_type=product&#038;p=7023"},"modified":"2026-01-29T13:45:58","modified_gmt":"2026-01-29T19:45:58","slug":"zhivago","status":"publish","type":"product","link":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/","title":{"rendered":"Zhivago"},"content":{"rendered":"<p>Precio vestido magenta, completamente nuevo, elegante y fresco. Perfecto para boda de d\u00eda o boda civil. <\/p>\n<p>Descuento: 20%<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talla: 10\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Desc: 20%<\/p>\n","protected":false},"featured_media":7024,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[135,31,22,192,1516],"product_tag":[440,638,1517,1520,1518,1519],"class_list":{"0":"post-7023","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-135","7":"product_cat-vestidos-coctel","8":"product_cat-vestidos-formales","9":"product_cat-rosa","10":"product_cat-zhivago","11":"product_tag-vestido-rosa","12":"product_tag-vestido-rosa-en-descuento","13":"product_tag-zhivago","14":"product_tag-zhivago-barato","15":"product_tag-zhivago-en-descuento","16":"product_tag-zhivago-nuevo","18":"first","19":"instock","20":"sale","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zhivago - Re Dress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redressmx.com\/index.php\/product\/zhivago\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zhivago - Re Dress\" \/>\n<meta property=\"og:description\" content=\"Talla: 10\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Desc: 20%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redressmx.com\/index.php\/product\/zhivago\/\" \/>\n<meta property=\"og:site_name\" content=\"Re Dress\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T19:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/11\/Fotos-Pagina-Web-15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/\",\"url\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/\",\"name\":\"Zhivago - Re Dress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fotos-Pagina-Web-15.png\",\"datePublished\":\"2024-11-27T18:19:20+00:00\",\"dateModified\":\"2026-01-29T19:45:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fotos-Pagina-Web-15.png\",\"contentUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Fotos-Pagina-Web-15.png\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/zhivago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/redressmx.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zhivago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#website\",\"url\":\"https:\\\/\\\/redressmx.com\\\/\",\"name\":\"Re Dress\",\"description\":\"Somos el marketplace de vestidos pre-loved m\u00e1s exclusivo de M\u00e9xico.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redressmx.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#organization\",\"name\":\"Re Dress\",\"url\":\"https:\\\/\\\/redressmx.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Grupo-144-2.png\",\"contentUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Grupo-144-2.png\",\"width\":345,\"height\":58,\"caption\":\"Re Dress\"},\"image\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zhivago - Re Dress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/","og_locale":"es_MX","og_type":"article","og_title":"Zhivago - Re Dress","og_description":"Talla: 10\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Desc: 20%","og_url":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/","og_site_name":"Re Dress","article_modified_time":"2026-01-29T19:45:58+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/11\/Fotos-Pagina-Web-15.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/","url":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/","name":"Zhivago - Re Dress","isPartOf":{"@id":"https:\/\/redressmx.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/#primaryimage"},"image":{"@id":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/#primaryimage"},"thumbnailUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/11\/Fotos-Pagina-Web-15.png","datePublished":"2024-11-27T18:19:20+00:00","dateModified":"2026-01-29T19:45:58+00:00","breadcrumb":{"@id":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redressmx.com\/index.php\/product\/zhivago\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/#primaryimage","url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/11\/Fotos-Pagina-Web-15.png","contentUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/11\/Fotos-Pagina-Web-15.png","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/redressmx.com\/index.php\/product\/zhivago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/redressmx.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/redressmx.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Zhivago"}]},{"@type":"WebSite","@id":"https:\/\/redressmx.com\/#website","url":"https:\/\/redressmx.com\/","name":"Re Dress","description":"Somos el marketplace de vestidos pre-loved m\u00e1s exclusivo de M\u00e9xico.","publisher":{"@id":"https:\/\/redressmx.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redressmx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redressmx.com\/#organization","name":"Re Dress","url":"https:\/\/redressmx.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redressmx.com\/#\/schema\/logo\/image\/","url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/02\/Grupo-144-2.png","contentUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/02\/Grupo-144-2.png","width":345,"height":58,"caption":"Re Dress"},"image":{"@id":"https:\/\/redressmx.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product\/7023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=7023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/media\/7024"}],"wp:attachment":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=7023"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=7023"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7023"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}