{"id":9866,"date":"2025-12-23T18:38:12","date_gmt":"2025-12-24T00:38:12","guid":{"rendered":"https:\/\/redressmx.com\/?post_type=product&#038;p=9866"},"modified":"2025-12-23T18:42:45","modified_gmt":"2025-12-24T00:42:45","slug":"novias-de-espana-8","status":"publish","type":"product","link":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/","title":{"rendered":"Novias de Espa\u00f1a"},"content":{"rendered":"<p>Vestido 100% nuevo, de la tienda de lujo &#8220;Novias de Espa\u00f1a&#8221;, color Ivory<\/p>\n<p>Descuento: 45%<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talla: 12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Desc: 45%<\/p>\n","protected":false},"featured_media":9867,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[180,139,29,30,89],"product_tag":[24,494,524,1849,242],"class_list":{"0":"post-9866","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-180","7":"product_cat-blanco","8":"product_cat-general","9":"product_cat-vestidos-novia","10":"product_cat-novias-de-espana","11":"product_tag-vestido-formal","12":"product_tag-vestido-formal-en-descuento","13":"product_tag-vestido-formal-preloved","14":"product_tag-vestido-formal-sale","15":"product_tag-vestido-mama-de-la-novia","17":"first","18":"instock","19":"sale","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novias de Espa\u00f1a - Re Dress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novias de Espa\u00f1a - Re Dress\" \/>\n<meta property=\"og:description\" content=\"Talla: 12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Desc: 45%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Re Dress\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-24T00:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redressmx.com\/wp-content\/uploads\/2025\/12\/Fotos-3-48.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/\",\"url\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/\",\"name\":\"Novias de Espa\u00f1a - Re Dress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Fotos-3-48.png\",\"datePublished\":\"2025-12-24T00:38:12+00:00\",\"dateModified\":\"2025-12-24T00:42:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Fotos-3-48.png\",\"contentUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Fotos-3-48.png\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/product\\\/novias-de-espana-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/redressmx.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/redressmx.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Novias de Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#website\",\"url\":\"https:\\\/\\\/redressmx.com\\\/\",\"name\":\"Re Dress\",\"description\":\"Somos el marketplace de vestidos pre-loved m\u00e1s exclusivo de M\u00e9xico.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redressmx.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#organization\",\"name\":\"Re Dress\",\"url\":\"https:\\\/\\\/redressmx.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/redressmx.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Grupo-144-2.png\",\"contentUrl\":\"https:\\\/\\\/redressmx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Grupo-144-2.png\",\"width\":345,\"height\":58,\"caption\":\"Re Dress\"},\"image\":{\"@id\":\"https:\\\/\\\/redressmx.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novias de Espa\u00f1a - Re Dress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/","og_locale":"es_MX","og_type":"article","og_title":"Novias de Espa\u00f1a - Re Dress","og_description":"Talla: 12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Desc: 45%","og_url":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/","og_site_name":"Re Dress","article_modified_time":"2025-12-24T00:42:45+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/redressmx.com\/wp-content\/uploads\/2025\/12\/Fotos-3-48.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/","url":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/","name":"Novias de Espa\u00f1a - Re Dress","isPartOf":{"@id":"https:\/\/redressmx.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/#primaryimage"},"image":{"@id":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/#primaryimage"},"thumbnailUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2025\/12\/Fotos-3-48.png","datePublished":"2025-12-24T00:38:12+00:00","dateModified":"2025-12-24T00:42:45+00:00","breadcrumb":{"@id":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/#primaryimage","url":"https:\/\/redressmx.com\/wp-content\/uploads\/2025\/12\/Fotos-3-48.png","contentUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2025\/12\/Fotos-3-48.png","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/redressmx.com\/index.php\/product\/novias-de-espana-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/redressmx.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/redressmx.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Novias de Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/redressmx.com\/#website","url":"https:\/\/redressmx.com\/","name":"Re Dress","description":"Somos el marketplace de vestidos pre-loved m\u00e1s exclusivo de M\u00e9xico.","publisher":{"@id":"https:\/\/redressmx.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redressmx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/redressmx.com\/#organization","name":"Re Dress","url":"https:\/\/redressmx.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/redressmx.com\/#\/schema\/logo\/image\/","url":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/02\/Grupo-144-2.png","contentUrl":"https:\/\/redressmx.com\/wp-content\/uploads\/2024\/02\/Grupo-144-2.png","width":345,"height":58,"caption":"Re Dress"},"image":{"@id":"https:\/\/redressmx.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product\/9866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=9866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/media\/9867"}],"wp:attachment":[{"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=9866"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=9866"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=9866"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/redressmx.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=9866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}